{"id":147,"count":12,"description":"","link":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/","name":"Arag\u00f3","slug":"arago","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arag\u00f3 archivos | Red Alimentacci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redalimentaccion.org\/ca\/.\/arago\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arag\u00f3 archivos | Red Alimentacci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redalimentaccion.org\/ca\/.\/arago\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Alimentacci\u00f3n\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/.\\\/arago\\\/\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/.\\\/arago\\\/\",\"name\":\"Arag\u00f3 archivos | Red Alimentacci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/.\\\/arago\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/.\\\/arago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arag\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#website\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/\",\"name\":\"Red Alimentacci\u00f3n\",\"description\":\"Red Alimentacci\u00f3n trabaja junto al sector educativo en la transformaci\u00f3n hacia un sistema alimentario saludable, justo, accesible y sostenible.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#organization\"},\"alternateName\":\"Alimentacci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redalimentaccion.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#organization\",\"name\":\"Red Alimentacci\u00f3n\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo_alimentaccion.png\",\"contentUrl\":\"https:\\\/\\\/redalimentaccion.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo_alimentaccion.png\",\"width\":835,\"height\":364,\"caption\":\"Red Alimentacci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arag\u00f3 archivos | Red Alimentacci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/","og_locale":"ca_ES","og_type":"article","og_title":"Arag\u00f3 archivos | Red Alimentacci\u00f3n","og_url":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/","og_site_name":"Red Alimentacci\u00f3n","og_image":[{"width":835,"height":364,"url":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/","url":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/","name":"Arag\u00f3 archivos | Red Alimentacci\u00f3n","isPartOf":{"@id":"https:\/\/redalimentaccion.org\/#website"},"breadcrumb":{"@id":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/redalimentaccion.org\/ca\/.\/arago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redalimentaccion.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Arag\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/redalimentaccion.org\/#website","url":"https:\/\/redalimentaccion.org\/","name":"Red Alimentacci\u00f3n","description":"Red Alimentacci\u00f3n trabaja junto al sector educativo en la transformaci\u00f3n hacia un sistema alimentario saludable, justo, accesible y sostenible.","publisher":{"@id":"https:\/\/redalimentaccion.org\/#organization"},"alternateName":"Alimentacci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redalimentaccion.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/redalimentaccion.org\/#organization","name":"Red Alimentacci\u00f3n","url":"https:\/\/redalimentaccion.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/redalimentaccion.org\/#\/schema\/logo\/image\/","url":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","contentUrl":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","width":835,"height":364,"caption":"Red Alimentacci\u00f3n"},"image":{"@id":"https:\/\/redalimentaccion.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/categories\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/posts?categories=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}