{"id":2813,"date":"2023-10-23T13:53:12","date_gmt":"2023-10-23T11:53:12","guid":{"rendered":"https:\/\/redalimentaccion.org\/entidad-colaboradora\/la-devanadera-rurales\/"},"modified":"2024-01-09T11:18:20","modified_gmt":"2024-01-09T10:18:20","slug":"la-devanadera-rurales","status":"publish","type":"entidad-colaboradora","link":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/","title":{"rendered":"La Devanadera Rurales"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1352px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:50px;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:50px;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:0px;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:24;--minFontSize:24;line-height:var(--awb-typography1-line-height);\"><h3>DESCRIPCI\u00d3<\/h3><\/h3><\/div><div class=\"fusion-text fusion-text-1\"><p>Som una associaci\u00f3 de dones bolcades a la cust\u00f2dia del territori. Operem a la Vall del Manubles, prov\u00edncia de Saragossa, una vall de gran tradici\u00f3 fruct\u00edcola. Treballem en la uni\u00f3 de producte-territori-patrimoni, usant, sempre que \u00e9s possible, eines del segle XXI. Una de les nostres l\u00ednies de treball \u00e9s la preservaci\u00f3 del guinder com a arbre i la recuperaci\u00f3 del seu \u00fas tradicional.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:24;--minFontSize:24;line-height:var(--awb-typography1-line-height);\"><h3>FAM\u00cdLIA PROFESSIONAL<\/h3><\/h3><\/div><div class=\"fusion-text fusion-text-2\"><ul>\n<li class=\"field-item even\">Agr\u00e0ria<\/li>\n<li class=\"field-item odd\">Serveis socioculturals i a la comunitat<\/li>\n<\/ul>\n<\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:24;--minFontSize:24;line-height:var(--awb-typography1-line-height);\"><h3>TIPUS DE COL\u00b7LABORACI\u00d3<\/h3><\/h3><\/div><div class=\"fusion-text fusion-text-3\"><ul>\n<li class=\"field-item even\">Participaci\u00f3 en tallers i xerrades<\/li>\n<li class=\"field-item odd\">Recepci\u00f3 d\u2019estudiants en pr\u00e0ctiques<\/li>\n<li class=\"field-item even\">Visites d\u2019estudiants a l\u2019entitat<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"featured_media":0,"template":"","tipo-de-entidad":[40],"class_list":["post-2813","entidad-colaboradora","type-entidad-colaboradora","status-publish","hentry","tipo-de-entidad-empresas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Devanadera Rurales | Red Alimentacci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Devanadera Rurales | Red Alimentacci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Alimentacci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-09T10:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/entidad-colaboradora\\\/la-devanadera-rurales\\\/\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/entidad-colaboradora\\\/la-devanadera-rurales\\\/\",\"name\":\"La Devanadera Rurales | Red Alimentacci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#website\"},\"datePublished\":\"2023-10-23T11:53:12+00:00\",\"dateModified\":\"2024-01-09T10:18:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/entidad-colaboradora\\\/la-devanadera-rurales\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/entidad-colaboradora\\\/la-devanadera-rurales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/entidad-colaboradora\\\/la-devanadera-rurales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redalimentaccion.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entidades colaboradoras\",\"item\":\"https:\\\/\\\/redalimentaccion.org\\\/entidad-colaboradora\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Devanadera Rurales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#website\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/\",\"name\":\"Red Alimentacci\u00f3n\",\"description\":\"Red Alimentacci\u00f3n trabaja junto al sector educativo en la transformaci\u00f3n hacia un sistema alimentario saludable, justo, accesible y sostenible.\",\"publisher\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#organization\"},\"alternateName\":\"Alimentacci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redalimentaccion.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#organization\",\"name\":\"Red Alimentacci\u00f3n\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redalimentaccion.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo_alimentaccion.png\",\"contentUrl\":\"https:\\\/\\\/redalimentaccion.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Logo_alimentaccion.png\",\"width\":835,\"height\":364,\"caption\":\"Red Alimentacci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/redalimentaccion.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Devanadera Rurales | Red Alimentacci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/","og_locale":"ca_ES","og_type":"article","og_title":"La Devanadera Rurales | Red Alimentacci\u00f3n","og_url":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/","og_site_name":"Red Alimentacci\u00f3n","article_modified_time":"2024-01-09T10:18:20+00:00","og_image":[{"width":835,"height":364,"url":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"10 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/","url":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/","name":"La Devanadera Rurales | Red Alimentacci\u00f3n","isPartOf":{"@id":"https:\/\/redalimentaccion.org\/#website"},"datePublished":"2023-10-23T11:53:12+00:00","dateModified":"2024-01-09T10:18:20+00:00","breadcrumb":{"@id":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/redalimentaccion.org\/ca\/entidad-colaboradora\/la-devanadera-rurales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redalimentaccion.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Entidades colaboradoras","item":"https:\/\/redalimentaccion.org\/entidad-colaboradora\/"},{"@type":"ListItem","position":3,"name":"La Devanadera Rurales"}]},{"@type":"WebSite","@id":"https:\/\/redalimentaccion.org\/#website","url":"https:\/\/redalimentaccion.org\/","name":"Red Alimentacci\u00f3n","description":"Red Alimentacci\u00f3n trabaja junto al sector educativo en la transformaci\u00f3n hacia un sistema alimentario saludable, justo, accesible y sostenible.","publisher":{"@id":"https:\/\/redalimentaccion.org\/#organization"},"alternateName":"Alimentacci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redalimentaccion.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/redalimentaccion.org\/#organization","name":"Red Alimentacci\u00f3n","url":"https:\/\/redalimentaccion.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/redalimentaccion.org\/#\/schema\/logo\/image\/","url":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","contentUrl":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/07\/Logo_alimentaccion.png","width":835,"height":364,"caption":"Red Alimentacci\u00f3n"},"image":{"@id":"https:\/\/redalimentaccion.org\/#\/schema\/logo\/image\/"}}]}},"toolset-meta":{"campos-entidades-colaboradoras":{"contacto-entidad":{"type":"wysiwyg","raw":"<div class=\"adr\">\n<div class=\"street-address\"><span class=\"postal-code\">50316<\/span> <span class=\"locality\">Bijuesca <\/span>, <span class=\"region\">ZR<\/span><\/div>\n<div><span class=\"additional\">Personas de contacte: Yolanda Gimeno Cuenca y Marta Estopi\u00f1an Mir<\/span><\/div>\n<\/div>\n<div class=\"map-link\">\n<div class=\"location map-link\">Vegeu mapa: <a href=\"http:\/\/maps.google.com\/?q=%2C+Bijuesca%2C+ZR%2C+50316%2C+es\">Google Maps<\/a><\/div>\n<\/div>"},"logo-entidad":{"type":"image","raw":"https:\/\/redalimentaccion.org\/wp-content\/uploads\/2023\/10\/La-Devanadera-Rurales_foto.jpg","attachment_id":2815},"descripcion-entidad":{"type":"textfield","raw":"associaci\u00f3 de dones bolcades a la cust\u00f2dia del territori."},"ubicacion-entidad":{"type":"google_address","raw":["50316 Bijuesca, Espa\u00f1a"]}}},"_links":{"self":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/entidad-colaboradora\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/entidad-colaboradora"}],"about":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/types\/entidad-colaboradora"}],"wp:attachment":[{"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/media?parent=2813"}],"wp:term":[{"taxonomy":"tipo-de-entidad","embeddable":true,"href":"https:\/\/redalimentaccion.org\/ca\/wp-json\/wp\/v2\/tipo-de-entidad?post=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}